{"id":76368,"date":"2021-10-29T18:50:07","date_gmt":"2021-10-29T13:20:07","guid":{"rendered":"https:\/\/www.ushasew.com\/lesson\/learn-to-sew-a-trendy-pleated-mask\/"},"modified":"2022-04-20T18:26:25","modified_gmt":"2022-04-20T12:56:25","slug":"learn-to-sew-a-trendy-pleated-mask","status":"publish","type":"lesson","link":"https:\/\/www.ushasew.com\/hi\/lesson\/learn-to-sew-a-trendy-pleated-mask\/","title":{"rendered":"\u091f\u094d\u0930\u0947\u0902\u0921\u0940 \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u092e\u093e\u0938\u094d\u0915 \u0938\u093f\u0932\u0928\u093e \u200b\u0938\u0940\u0916\u0947\u0902"},"content":{"rendered":"","protected":false},"featured_media":0,"menu_order":159,"template":"","lesson_language":[281],"class_list":["post-76368","lesson","type-lesson","status-publish","hentry","lesson_language-english-hi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u091f\u094d\u0930\u0947\u0902\u0921\u0940 \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u092e\u093e\u0938\u094d\u0915 \u0938\u093f\u0932\u0928\u093e \u200b\u0938\u0940\u0916\u0947\u0902 - USHA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ushasew.com\/hi\/lesson\/learn-to-sew-a-trendy-pleated-mask\/\" \/>\n<meta property=\"og:locale\" content=\"hi_IN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u091f\u094d\u0930\u0947\u0902\u0921\u0940 \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u092e\u093e\u0938\u094d\u0915 \u0938\u093f\u0932\u0928\u093e \u200b\u0938\u0940\u0916\u0947\u0902 - USHA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ushasew.com\/hi\/lesson\/learn-to-sew-a-trendy-pleated-mask\/\" \/>\n<meta property=\"og:site_name\" content=\"USHA\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-20T12:56:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ushasew.com\\\/hi\\\/lesson\\\/learn-to-sew-a-trendy-pleated-mask\\\/\",\"url\":\"https:\\\/\\\/www.ushasew.com\\\/hi\\\/lesson\\\/learn-to-sew-a-trendy-pleated-mask\\\/\",\"name\":\"\u091f\u094d\u0930\u0947\u0902\u0921\u0940 \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u092e\u093e\u0938\u094d\u0915 \u0938\u093f\u0932\u0928\u093e \u200b\u0938\u0940\u0916\u0947\u0902 - USHA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beta.ushasew.com\\\/#website\"},\"datePublished\":\"2021-10-29T13:20:07+00:00\",\"dateModified\":\"2022-04-20T12:56:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ushasew.com\\\/hi\\\/lesson\\\/learn-to-sew-a-trendy-pleated-mask\\\/#breadcrumb\"},\"inLanguage\":\"hi-IN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ushasew.com\\\/hi\\\/lesson\\\/learn-to-sew-a-trendy-pleated-mask\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ushasew.com\\\/hi\\\/lesson\\\/learn-to-sew-a-trendy-pleated-mask\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u092e\u0941\u0916\u094d\u092f\",\"item\":\"https:\\\/\\\/beta.ushasew.com\\\/hi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u091f\u094d\u0930\u0947\u0902\u0921\u0940 \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u092e\u093e\u0938\u094d\u0915 \u0938\u093f\u0932\u0928\u093e \u200b\u0938\u0940\u0916\u0947\u0902\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beta.ushasew.com\\\/#website\",\"url\":\"https:\\\/\\\/beta.ushasew.com\\\/\",\"name\":\"USHA\",\"description\":\"Learn &amp; Create\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beta.ushasew.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hi-IN\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u091f\u094d\u0930\u0947\u0902\u0921\u0940 \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u092e\u093e\u0938\u094d\u0915 \u0938\u093f\u0932\u0928\u093e \u200b\u0938\u0940\u0916\u0947\u0902 - USHA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ushasew.com\/hi\/lesson\/learn-to-sew-a-trendy-pleated-mask\/","og_locale":"hi_IN","og_type":"article","og_title":"\u091f\u094d\u0930\u0947\u0902\u0921\u0940 \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u092e\u093e\u0938\u094d\u0915 \u0938\u093f\u0932\u0928\u093e \u200b\u0938\u0940\u0916\u0947\u0902 - USHA","og_url":"https:\/\/www.ushasew.com\/hi\/lesson\/learn-to-sew-a-trendy-pleated-mask\/","og_site_name":"USHA","article_modified_time":"2022-04-20T12:56:25+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ushasew.com\/hi\/lesson\/learn-to-sew-a-trendy-pleated-mask\/","url":"https:\/\/www.ushasew.com\/hi\/lesson\/learn-to-sew-a-trendy-pleated-mask\/","name":"\u091f\u094d\u0930\u0947\u0902\u0921\u0940 \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u092e\u093e\u0938\u094d\u0915 \u0938\u093f\u0932\u0928\u093e \u200b\u0938\u0940\u0916\u0947\u0902 - USHA","isPartOf":{"@id":"https:\/\/beta.ushasew.com\/#website"},"datePublished":"2021-10-29T13:20:07+00:00","dateModified":"2022-04-20T12:56:25+00:00","breadcrumb":{"@id":"https:\/\/www.ushasew.com\/hi\/lesson\/learn-to-sew-a-trendy-pleated-mask\/#breadcrumb"},"inLanguage":"hi-IN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ushasew.com\/hi\/lesson\/learn-to-sew-a-trendy-pleated-mask\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ushasew.com\/hi\/lesson\/learn-to-sew-a-trendy-pleated-mask\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u092e\u0941\u0916\u094d\u092f","item":"https:\/\/beta.ushasew.com\/hi\/"},{"@type":"ListItem","position":2,"name":"\u091f\u094d\u0930\u0947\u0902\u0921\u0940 \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u092e\u093e\u0938\u094d\u0915 \u0938\u093f\u0932\u0928\u093e \u200b\u0938\u0940\u0916\u0947\u0902"}]},{"@type":"WebSite","@id":"https:\/\/beta.ushasew.com\/#website","url":"https:\/\/beta.ushasew.com\/","name":"USHA","description":"Learn &amp; Create","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beta.ushasew.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hi-IN"}]}},"_links":{"self":[{"href":"https:\/\/www.ushasew.com\/hi\/wp-json\/wp\/v2\/lesson\/76368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ushasew.com\/hi\/wp-json\/wp\/v2\/lesson"}],"about":[{"href":"https:\/\/www.ushasew.com\/hi\/wp-json\/wp\/v2\/types\/lesson"}],"wp:attachment":[{"href":"https:\/\/www.ushasew.com\/hi\/wp-json\/wp\/v2\/media?parent=76368"}],"wp:term":[{"taxonomy":"lesson_language","embeddable":true,"href":"https:\/\/www.ushasew.com\/hi\/wp-json\/wp\/v2\/lesson_language?post=76368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}